{"id":39741,"date":"2023-10-10T14:57:43","date_gmt":"2023-10-10T21:57:43","guid":{"rendered":"https:\/\/www.monetizemore.com\/?p=39741"},"modified":"2023-10-10T14:57:43","modified_gmt":"2023-10-10T21:57:43","slug":"o-que-e-lance-em-tempo-real-rtb","status":"publish","type":"post","link":"https:\/\/www.monetizemore.com\/pt-br\/blog\/o-que-e-lance-em-tempo-real-rtb\/","title":{"rendered":"O Que \u00c9 Lance Em Tempo Real (Rtb)? &#8211; Guia De Compra Program\u00e1tica, Plataformas E Redes De An\u00fancios"},"content":{"rendered":"<p>O setor de RTB (Real Time Bidding) ou lances em tempo real tem aumentado, \u00e0 medida que a m\u00eddia program\u00e1tica continua ganhando for\u00e7a. Isso se traduz em bilh\u00f5es de d\u00f3lares.<img  title=\"O Que \u00c9 Lance Em Tempo Real (Rtb)? - Guia De Compra Program\u00e1tica, Plataformas E Redes De An\u00fancios MonitizeMore\" decoding=\"async\" class=\"alignright wp-image-7642\" src=\"https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/vector-laptop.png\"  alt=\"O Que \u00c9 Lance Em Tempo Real (Rtb)? - Guia De Compra Program\u00e1tica, Plataformas E Redes De An\u00fancios MonitizeMore\"  width=\"300\" height=\"251\" srcset=\"https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/vector-laptop.png 640w, https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/vector-laptop-300x251.png 300w, https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/vector-laptop-595xh.png 595w, https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/vector-laptop-480x401.png 480w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/p>\n<p>Com taxas de crescimento sem precedentes e mais empresas adotando o uso dessas t\u00e9cnicas de publicidade program\u00e1tica, \u00e9 seguro dizer que voc\u00ea precisa entender de RTB se voc\u00ea \u00e9 um anunciante, editor ou simplesmente um comerciante que trabalha com ambas as partes.<\/p>\n<p>Aqui consideraremos todos os aspectos e garantiremos que voc\u00ea saia como um especialista na \u00e1rea!<\/p>\n<table style=\"background-color: #e0ecf8; border: 2px solid #712b5a;\">\n<tbody>\n<tr>\n<td>\n<p style=\"text-align: center;\"><a id=\"post-12134-newsletter-cta\" class=\"inbound cta\" href=\"https:\/\/www.monetizemore.com\/subscribe-to-the-monetizemore-newsletter-pt\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><span style=\"text-decoration: underline; color: #008000;\">Quer as melhores dicas para aumentar sua receita e saber de tudo o que acontece no mundo da otimiza\u00e7\u00e3o de an\u00fancios, Header Bidding e Ad Tech? Assine a nossa Newsletter e n\u00e3o perca nenhuma dica ou tend\u00eancia da ind\u00fastria.<\/span><\/strong><\/a><\/p>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>Como Funcionam Os Lances Em Tempo Real (RTB)<\/h2>\n<p><img  title=\"O Que \u00c9 Lance Em Tempo Real (Rtb)? - Guia De Compra Program\u00e1tica, Plataformas E Redes De An\u00fancios MonitizeMore\" decoding=\"async\" class=\" wp-image-6807 alignright\" src=\"https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/what-is-real-tb.jpg\"  alt=\"O Que \u00c9 Lance Em Tempo Real (Rtb)? - Guia De Compra Program\u00e1tica, Plataformas E Redes De An\u00fancios MonitizeMore\"  width=\"351\" height=\"527\" srcset=\"https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/what-is-real-tb.jpg 500w, https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/what-is-real-tb-200x300.jpg 200w, https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/what-is-real-tb-480x720.jpg 480w\" sizes=\"(max-width: 351px) 100vw, 351px\" \/>Antes de entrarmos em detalhes, eu gostaria de explicar o que \u00e9 RTB. Isso te dar\u00e1 uma melhor compreens\u00e3o dos processos e plataformas mencionados no restante deste artigo.<\/p>\n<p>Se esta \u00e9 a primeira vez que voc\u00ea descobre m\u00eddia program\u00e1tica, reserve um momento para ler nosso artigo <a href=\"https:\/\/www.monetizemore.com\/blog\/programmatic-advertising-explained\/\">O guia completo da m\u00eddia program\u00e1tica<\/a>, para obter algumas informa\u00e7\u00f5es b\u00e1sicas sobre esse setor de publicidade orientado pela tecnologia.<\/p>\n<h3>O que \u00e9 RTB (Real Time Bidding)?<\/h3>\n<p>Lances em tempo real (Real Time Bidding) \u00e9 uma configura\u00e7\u00e3o de leil\u00e3o em que as impress\u00f5es de an\u00fancios s\u00e3o\u00a0 compradas e vendidas em transa\u00e7\u00f5es que ocorrem em um piscar de olhos. Depois que o lance de um anunciante vence o leil\u00e3o, o an\u00fancio digital \u00e9 exibido instantaneamente no site ou na propriedade do editor.<\/p>\n<p>Plataformas de suporte, como Ad Exchange e plataformas de invent\u00e1rio, tamb\u00e9m s\u00e3o usadas no processo. Os leil\u00f5es de RTB concentram-se nos lances com base em impress\u00f5es, enquanto os leil\u00f5es est\u00e1ticos tendem a agrupar impress\u00f5es, de modo que os anunciantes podem vender apenas pacotes de impress\u00f5es.<\/p>\n<h3>Como o lance em tempo real funciona?<\/h3>\n<p class=\"p2\">Para compreender como funciona o processo de RTB, \u00e9 necess\u00e1rio conhecer os agentes que atuam neste tipo de negocia\u00e7\u00e3o:<\/p>\n<ul class=\"ul1\">\n<li class=\"li2\"><strong>Plataformas de oferta (SSP)<\/strong>: representam o lado dos vendedores, em que diversos editores parceiros da plataforma disponibilizam seus invent\u00e1rio de an\u00fancios para venda;<\/li>\n<li class=\"li2\"><strong>Plataformas de demanda (DSP)<\/strong>: atuam para os compradores, em que seus esfor\u00e7os s\u00e3o direcionados para encontrar o invent\u00e1rio com melhor custo\/benef\u00edcio para exposi\u00e7\u00e3o de uma marca ou campanha;<\/li>\n<li class=\"li2\"><strong>Ad Exchange<\/strong>: funciona como um intermedi\u00e1rio da negocia\u00e7\u00e3o, e pode ser entendido como um marketplace para a negocia\u00e7\u00e3o de espa\u00e7os publicit\u00e1rios.<\/li>\n<\/ul>\n<p><img  title=\"O Que \u00c9 Lance Em Tempo Real (Rtb)? - Guia De Compra Program\u00e1tica, Plataformas E Redes De An\u00fancios MonitizeMore\" decoding=\"async\" src=\"https:\/\/pt.pubguru.com\/wp-content\/uploads\/sites\/3\/2022\/05\/IMGs_Blog_M2.png\"  alt=\"O Que \u00c9 Lance Em Tempo Real (Rtb)? - Guia De Compra Program\u00e1tica, Plataformas E Redes De An\u00fancios MonitizeMore\"  \/><\/p>\n<p>Vamos ao processo:<\/p>\n<p>Quando um usu\u00e1rio visita um site, uma solicita\u00e7\u00e3o de lance \u00e9 enviada ao Ad Exchange.<\/p>\n<p>Essa solicita\u00e7\u00e3o de lance cont\u00e9m variadas informa\u00e7\u00f5es, como dados demogr\u00e1ficos, informa\u00e7\u00f5es de localiza\u00e7\u00e3o, hist\u00f3rico do navegador, etc. O Ad Exchange passa as solicita\u00e7\u00f5es de lance para sua lista de anunciantes \/ compradores, que fazem lances em tempo real para a compra da impress\u00e3o do an\u00fancio, como ela ser\u00e1 apresentada ao usu\u00e1rio do site. O anunciante que oferece o maior valor ganha a impress\u00e3o e exibe seu an\u00fancio para o usu\u00e1rio do site.<\/p>\n<p>Esse mesmo processo \u00e9 repetido v\u00e1rias vezes para cada bloco de an\u00fancios de cada p\u00e1gina de um site. Esse procedimento ocorre em 100 milissegundos, incluindo o recebimento da solicita\u00e7\u00e3o de lance e a veicula\u00e7\u00e3o do an\u00fancio. RTB \u00e9 a cria\u00e7\u00e3o de um ecossistema de publicidade eficiente!<\/p>\n<p><iframe title=\"How an Ad is Served with Real Time Bidding (RTB) - IAB Digital Simplified\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/-Glgi9RRuJs?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>D\u00ea uma olhada neste outro infogr\u00e1fico em Whoishostingthis.com, para obter uma vis\u00e3o geral do processo de RTB.<\/p>\n<p><img  title=\"O Que \u00c9 Lance Em Tempo Real (Rtb)? - Guia De Compra Program\u00e1tica, Plataformas E Redes De An\u00fancios MonitizeMore\" decoding=\"async\" src=\"https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/Everything-you-need-to-know-about-Real-Time-Bidding-ver.2.jpg\"  alt=\"O Que \u00c9 Lance Em Tempo Real (Rtb)? - Guia De Compra Program\u00e1tica, Plataformas E Redes De An\u00fancios MonitizeMore\"  \/><\/p>\n<h2>Lances Em Tempo Real vs. M\u00eddia Program\u00e1tica<\/h2>\n<p>\u00c9 f\u00e1cil misturar todos os termos da ind\u00fastria do marketing digital. Se voc\u00ea est\u00e1 se perguntando sobre RTB vs. m\u00eddia program\u00e1tica e se essas terminologias significam a mesma coisa, n\u00e3o procure mais. Ali\u00e1s, j\u00e1 te digo que esses dois n\u00e3o s\u00e3o a mesma coisa.<\/p>\n<p>Voc\u00ea pode pensar na m\u00eddia program\u00e1tica como a rainha dos an\u00fancios digitais, voltada para a tecnologia que vende e compra o mundo, enquanto o RTB \u00e9 uma parte ou faceta cr\u00edtica dela.<\/p>\n<p>O RTB desempenha um papel significativo no reino program\u00e1tico e pode ser classificado como um tipo de m\u00eddia program\u00e1tica, n\u00e3o como uma m\u00eddia program\u00e1tica. Alguns editores podem at\u00e9 vender seu invent\u00e1rio sem o uso de RTB atrav\u00e9s de m\u00e9todos como program\u00e1tica garantida ou direta.<\/p>\n<p>Na pr\u00f3xima se\u00e7\u00e3o, a compara\u00e7\u00e3o com Ad Exchange fornecer\u00e1 uma melhor compreens\u00e3o.<\/p>\n<h2>An\u00fancios De Rtb Vs. Trocas De An\u00fancios (Ad Exchange)<\/h2>\n<p>Da mesma forma que na explica\u00e7\u00e3o anterior, os lances em tempo real e a troca de an\u00fancios n\u00e3o s\u00e3o os mesmos. As trocas de an\u00fancios desempenham um papel significativo na m\u00eddia program\u00e1tica e s\u00e3o uma engrenagem vital na m\u00e1quina de RTB, conforme mostrado na imagem abaixo, do IAB (Interactive Advertising Bureau).<\/p>\n<p>Esta imagem pode te ajudar a ter uma vis\u00e3o mais ampla do ecossistema de m\u00eddia program\u00e1tica.<\/p>\n<p><img  title=\"O Que \u00c9 Lance Em Tempo Real (Rtb)? - Guia De Compra Program\u00e1tica, Plataformas E Redes De An\u00fancios MonitizeMore\" decoding=\"async\" class=\"alignnone wp-image-6809 size-full\" src=\"https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/main-qimg-5256b27b1bfbb128b9220b7972378eb4.jpg\"  alt=\"O Que \u00c9 Lance Em Tempo Real (Rtb)? - Guia De Compra Program\u00e1tica, Plataformas E Redes De An\u00fancios MonitizeMore\"  width=\"602\" height=\"412\" srcset=\"https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/main-qimg-5256b27b1bfbb128b9220b7972378eb4.jpg 602w, https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/main-qimg-5256b27b1bfbb128b9220b7972378eb4-300x205.jpg 300w, https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/main-qimg-5256b27b1bfbb128b9220b7972378eb4-595xh.jpg 595w, https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/main-qimg-5256b27b1bfbb128b9220b7972378eb4-480x329.jpg 480w\" sizes=\"(max-width: 602px) 100vw, 602px\" \/><\/p>\n<p>Fonte da imagem: <a href=\"https:\/\/www.quora.com\/What-is-the-Difference-between-an-Ad-Exchange-and-RTB\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.quora.com\/What-is-the-Difference-between-an-Ad-Exchange-and-RTB<\/a><\/p>\n<p>Como demonstrado, o processo de compra e venda de invent\u00e1rio de an\u00fancios por impress\u00e3o, que s\u00e3o as trocas de an\u00fancios, atuam como a plataforma na qual editores e anunciantes se re\u00fanem para o intercambio de invent\u00e1rio de an\u00fancios digitais<\/p>\n<p>Este marketplace (Ad Exchange) usa DSPs (plataformas de demanda) para avaliar o invent\u00e1rio de an\u00fancios dispon\u00edvel para os anunciantes. Se a impress\u00e3o corresponder ao p\u00fablico-alvo do anunciante, um lance ser\u00e1 feito por meio do DSP e, se conquistado, o an\u00fancio ser\u00e1 entregue no site do editor.<\/p>\n<h2>Lances Em Tempo Real Vs. DSPs (Plataformas De Demanda)<\/h2>\n<p>Conforme descrito na imagem do IAB acima, uma DSP (Demand Side Platform) tamb\u00e9m \u00e9 um componente do RTB que, como a maioria das facetas da m\u00eddia program\u00e1tica, desempenha um papel complexo. Se voc\u00ea ainda n\u00e3o conhece essas plataformas, leia nosso guia sobre \u201cO que \u00e9 uma plataforma de demanda (DSP)\u201d <a href=\"https:\/\/www.monetizemore.com\/blog\/demand-side-platform-dsp\/\">aqui<\/a>.<\/p>\n<p>Aqui est\u00e1 uma pequena compara\u00e7\u00e3o feita pelo <a href=\"http:\/\/www.knowonlineadvertising.com\/difference-between\/difference-between-dsp-and-rtb\/\" target=\"_blank\" rel=\"noopener noreferrer\">Knowonlineadvertising.com<\/a>.<\/p>\n<p>As plataformas de demanda, s\u00e3o programas atrav\u00e9s dos quais o invent\u00e1rio de an\u00fancios digitais \u00e9 comprado pelos anunciantes, enquanto o RTB \u00e9 o mecanismo usado para comprar esse invent\u00e1rio.<\/p>\n<p>As plataformas de suprimentos beneficiam o anunciante, ajudando-o a obter acesso a v\u00e1rias trocas de RTB por meio de um \u00fanico painel de acesso, para facilitar o uso e a efici\u00eancia do gerenciamento de campanhas de an\u00fancios.<\/p>\n<p>Os DSPs compram impress\u00f5es com base em informa\u00e7\u00f5es do p\u00fablico-alvo, como dados comportamentais, enquanto a tecnologia de lances faz o lance de acordo com o p\u00fablico j\u00e1 escolhido.<\/p>\n<h2>Benef\u00edcios Para Editores<\/h2>\n<p><img  title=\"O Que \u00c9 Lance Em Tempo Real (Rtb)? - Guia De Compra Program\u00e1tica, Plataformas E Redes De An\u00fancios MonitizeMore\" decoding=\"async\" class=\"alignright wp-image-6810\" src=\"https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/real-tb-benefits-publishers.jpg\"  alt=\"O Que \u00c9 Lance Em Tempo Real (Rtb)? - Guia De Compra Program\u00e1tica, Plataformas E Redes De An\u00fancios MonitizeMore\"  width=\"351\" height=\"527\" srcset=\"https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/real-tb-benefits-publishers.jpg 500w, https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/real-tb-benefits-publishers-200x300.jpg 200w, https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/real-tb-benefits-publishers-480x720.jpg 480w\" sizes=\"(max-width: 351px) 100vw, 351px\" \/>\u00c9 muito bom entender onde a m\u00eddia program\u00e1tica, as trocas de an\u00fancios e as plataformas de demanda se encaixam na equa\u00e7\u00e3o, mas e o editor? O RTB beneficia o editor de alguma forma? O <a href=\"https:\/\/econsultancy.com\/six-advantages-of-real-time-bidding-for-publishers\/\" target=\"_blank\" rel=\"noopener noreferrer\">Econsultancy.com<\/a> identificou seis benef\u00edcios para o editor, incluindo:<\/p>\n<p><b>Pre\u00e7os acurados medidos pela tecnologia:<\/b> os editores recebem mais valor para seu invent\u00e1rio com RTB, pois cada impress\u00e3o pode receber lances pelos anunciantes e precisamente o lance de valor mais alto \u00e9 o que pode levar a impress\u00e3o. Um editor frequentemente precisa usar um SSP (Supply Side Platform ou Plataformas de Suprimentos) para fazer lances em tempo real.<\/p>\n<p><b>Aumento do valor do estoque remanescente:<\/b> como editor, voc\u00ea deseja gerar receita com o m\u00e1ximo poss\u00edvel do seu estoque. Com o RTB, o estoque anteriormente considerado n\u00e3o monetiz\u00e1vel ou n\u00e3o valioso, pode ser utilizado pelos anunciantes que fazem lances com base nos dados do p\u00fablico. A Econsultancy informou que mais de 40% dos editores observaram um aumento no valor de seu estoque remanescente ao participar de leil\u00f5es de RTB.<\/p>\n<p><b>Controle via SSPs:<\/b> como mencionado, um editor precisa trabalhar com uma plataforma de suprimentos para participar de leil\u00f5es de RTB. No entanto, isso significa que o editor tomou o controle do seu invent\u00e1rio, como especificar quais anunciantes podem comprar seu invent\u00e1rio de an\u00fancios e definir o pre\u00e7o.<\/p>\n<p><b>Entendendo melhor o p\u00fablico-alvo: <\/b>como editor, geralmente \u00e9 dif\u00edcil saber qual segmento do seu p\u00fablico merece mais aten\u00e7\u00e3o, pelo menos do ponto de vista monet\u00e1rio. Usando essa tecnologia, os editores podem determinar quais tipos de p\u00fablico interessam mais aos anunciantes e obt\u00eam os melhores pre\u00e7os. Isso pode fornecer a um editor, informa\u00e7\u00f5es valiosas e ajud\u00e1-lo a expandir seus sites em seus segmentos mais lucrativos, aumentando o valor do invent\u00e1rio e a demanda dos anunciantes.<\/p>\n<p><b>Para editores premium fazerem uso de mercados privados<\/b>: em mercados privados, apenas um grupo definido de anunciantes pode fazer lances no invent\u00e1rio de an\u00fancios de um editor. Com RTB e mercados privados, os editores podem vender seu material publicit\u00e1rio com ainda mais transpar\u00eancia e controle.<\/p>\n<p><b>Melhor desempenho em vendas diretas:<\/b> se um editor deseja vender seu invent\u00e1rio diretamente para anunciantes que trabalham com SSPs, os lances em tempo real podem fornecer informa\u00e7\u00f5es valiosas sobre os segmentos de invent\u00e1rio mais lucrativos. Um editor pode determinar em quais partes as pe\u00e7as s\u00e3o mais procuradas e usar essas informa\u00e7\u00f5es para vender seu estoque diretamente \u00e0s partes interessadas com sucesso.<\/p>\n<h2>Benef\u00edcios Para Anunciantes<\/h2>\n<p><img  title=\"O Que \u00c9 Lance Em Tempo Real (Rtb)? - Guia De Compra Program\u00e1tica, Plataformas E Redes De An\u00fancios MonitizeMore\" decoding=\"async\" class=\" wp-image-6814 alignright\" src=\"https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/adbentr.jpg\"  alt=\"O Que \u00c9 Lance Em Tempo Real (Rtb)? - Guia De Compra Program\u00e1tica, Plataformas E Redes De An\u00fancios MonitizeMore\"  width=\"350\" height=\"525\" srcset=\"https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/adbentr.jpg 400w, https:\/\/www.monetizemore.com\/wp-content\/uploads\/2017\/09\/adbentr-200x300.jpg 200w\" sizes=\"(max-width: 350px) 100vw, 350px\" \/>Do ponto de vista dos compradores \/ anunciantes, o <a href=\"https:\/\/econsultancy.com\/what-are-the-advantages-of-rtb-for-buying-display-advertising\/\" target=\"_blank\" rel=\"noopener noreferrer\">Econsultancy.com<\/a> descreve o RTB como uma forma de PPC ou marketing pago por clique. A maioria das empresas ou anunciantes, que j\u00e1 tentaram comercializar um produto ou servi\u00e7o online, estar\u00e1 familiarizada com esse termo. Anunciar via Facebook ou Google AdWords \u00e9 um bom exemplo de PPC.<\/p>\n<p>Com esta breve introdu\u00e7\u00e3o, aqui est\u00e3o quatro benef\u00edcios do RTB para a compra de publicidade de display:<\/p>\n<p><b>Compra de m\u00eddia com menos desperd\u00edcio: <\/b>\u00a0com essa tecnologia, o invent\u00e1rio de an\u00fancios \u00e9 comprado com base em impress\u00f5es por meio de um rango de vari\u00e1veis, o que torna a segmenta\u00e7\u00e3o muito focada. Um anunciante n\u00e3o precisa comprar invent\u00e1rio de an\u00fancios em massa e correr o risco de desperdi\u00e7ar dinheiro com visitantes n\u00e3o segmentados ou irrelevantes do site. T\u00e9cnicas e ferramentas avan\u00e7adas, como limite de frequ\u00eancia e previs\u00e3o de lances, podem aumentar a efici\u00eancia de cada campanha, permitindo que os anunciantes testem, controlem, avaliem e at\u00e9 prevejam determinadas vari\u00e1veis \u200b\u200bda campanha.<\/p>\n<p><b>Campanhas com melhor desempenho:<\/b> os anunciantes podem visualizar e gerenciar suas campanhas em tempo real por meio de um painel e ajustar lances e segmenta\u00e7\u00e3o conforme necess\u00e1rio, mantendo assim os resultados e melhorando o desempenho.<\/p>\n<p><b>Conhecimento aprofundado:<\/b> durante a execu\u00e7\u00e3o de campanhas com RTB, os anunciantes podem transformar e melhorar suas estrat\u00e9gias de marketing. Eles podem aprender mais e entender seus consumidores, melhorar a abordagem criativa e estrat\u00e9gica com os dados de impress\u00e3o apresentados a eles por meio de suas campanhas.<\/p>\n<p><b>Prote\u00e7\u00e3o de marca:<\/b> para um anunciante, proteger sua marca \u00e9 muito importante. Com os lances em tempo real, os anunciantes podem especificar onde promover seus produtos ou servi\u00e7os, e usar os servi\u00e7os de verifica\u00e7\u00e3o de an\u00fancios para impedir que seus an\u00fancios sejam exibidos em sites ou p\u00e1ginas il\u00edcitos.<\/p>\n<h2>O Pr\u00f3ximo N\u00edvel De Desenvolvimento Com O Openrtb 3.0<\/h2>\n<p>O Laborat\u00f3rio de Tecnologia da IAB lan\u00e7ou em 2017, a solu\u00e7\u00e3o <a href=\"https:\/\/iabtechlab.com\/standards\/openrtb\/\" target=\"_blank\" rel=\"noopener noreferrer\">OpenRTB 3.0<\/a>, uma vers\u00e3o atualizada do Real Time Bidding (Lances em Tempo Real) original de 2010, para o p\u00fablico, para seu per\u00edodo inicial de coment\u00e1rios. O foco desta vers\u00e3o era aumentar a seguran\u00e7a e a confian\u00e7a, oferecendo melhor transpar\u00eancia aos compradores e integrando melhorias recentes no setor, como a iniciativa <a href=\"https:\/\/www.monetizemore.com\/blog\/manual-ads-txt-do-publisher-um-guia-para-a-implementacao\/\" target=\"_blank\" rel=\"noopener noreferrer\">Ads.txt<\/a>.<\/p>\n<p><b>Algumas das atualiza\u00e7\u00f5es da estrutura foram:<\/b><\/p>\n<ul>\n<li style=\"font-weight: 400;\">Um processo de solicita\u00e7\u00e3o de lance assinado criptograficamente que ajudar\u00e1 os compradores a ver o fluxo do estoque e a confirmar a cadeia de suprimentos real.<\/li>\n<li style=\"font-weight: 400;\">Um novo modelo de marketing de an\u00fancios para oferecer aos editores um melhor controle dos elementos gr\u00e1ficos e da experi\u00eancia do usu\u00e1rio em seus sites. Este modelo destacar\u00e1 toda e qualquer altera\u00e7\u00e3o feita nas pe\u00e7as criativas dos an\u00fancios.<\/li>\n<li style=\"font-weight: 400;\">Um novo padr\u00e3o de gerenciamento de an\u00fancios API para otimizar o processo de aprova\u00e7\u00e3o de pe\u00e7as criativas de anunciantes, facilitando desenvolvimentos futuros e outras integra\u00e7\u00f5es.<\/li>\n<\/ul>\n<h2 class=\"p4\">Principais plataformas de RTB para editores<\/h2>\n<p class=\"p2\">Confira abaixo as principais plataformas (para venda de espa\u00e7os em sites e apps) de negocia\u00e7\u00e3o por leil\u00e3o em tempo real para editores:<\/p>\n<ul class=\"ul1\">\n<li class=\"li2\">OpenX;<\/li>\n<li class=\"li2\">AppNexus;<\/li>\n<li class=\"li2\">PubMatic;<\/li>\n<li>Google Ad Manager;<\/li>\n<li class=\"li2\">Smaato;<\/li>\n<li class=\"li2\">Rubicon Project;<\/li>\n<li class=\"li2\">Sitescout.<\/li>\n<\/ul>\n<h2>Conclus\u00e3o<\/h2>\n<p>O uso de lances em tempo real (Real Time Bidding) est\u00e1 aumentando \u00e0 medida que mais anunciantes mudam para uma abordagem de publicidade program\u00e1tica e com o desenvolvimento de novas vers\u00f5es, como o OpenRTB 3.0. \u00c9 uma fase realmente empolgante para editores e anunciantes, com o mundo da publicidade digital crescendo continuamente e com mais formatos de an\u00fancios entrando na arena da m\u00eddia program\u00e1tica.<\/p>\n<p>O potencial para otimiza\u00e7\u00e3o de RTB \u00e9 enorme! Para desbloquear esse potencial, \u00e9 necess\u00e1rio um especialista em RTB. <a href=\"https:\/\/www.monetizemore.com\/sign-up-pt\/?utm_source=organic&amp;utm_medium=blog&amp;utm_campaign=real-time-bidding-explained-pt-bottom&amp;utm_adgroup=mari\">Inscreva-se na MonetizeMore para ter acesso a um especialista em RTB hoje mesmo!<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O setor de RTB (Real Time Bidding) ou lances em tempo real tem aumentado, \u00e0 medida que a m\u00eddia program\u00e1tica continua ganhando for\u00e7a. Isso se traduz em bilh\u00f5es de d\u00f3lares. Com taxas de crescimento sem precedentes e mais empresas adotando o uso dessas t\u00e9cnicas de publicidade program\u00e1tica, \u00e9 seguro dizer que voc\u00ea precisa entender de [&hellip;]<\/p>\n","protected":false},"author":72,"featured_media":39742,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[2254,2251],"tags":[],"class_list":["post-39741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-definicoes-da-industria-de-adtech","category-midia-programatica"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.monetizemore.com\/pt-br\/wp-json\/wp\/v2\/posts\/39741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.monetizemore.com\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.monetizemore.com\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.monetizemore.com\/pt-br\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.monetizemore.com\/pt-br\/wp-json\/wp\/v2\/comments?post=39741"}],"version-history":[{"count":0,"href":"https:\/\/www.monetizemore.com\/pt-br\/wp-json\/wp\/v2\/posts\/39741\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.monetizemore.com\/pt-br\/wp-json\/wp\/v2\/media\/39742"}],"wp:attachment":[{"href":"https:\/\/www.monetizemore.com\/pt-br\/wp-json\/wp\/v2\/media?parent=39741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.monetizemore.com\/pt-br\/wp-json\/wp\/v2\/categories?post=39741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.monetizemore.com\/pt-br\/wp-json\/wp\/v2\/tags?post=39741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}